{"id":7624,"date":"2019-01-30T09:41:00","date_gmt":"2019-01-30T08:41:00","guid":{"rendered":"https:\/\/www.bephila.be\/?p=7624"},"modified":"2026-01-30T10:51:50","modified_gmt":"2026-01-30T09:51:50","slug":"uitgiften-2026-voorverkoop-4-la-louviere","status":"publish","type":"post","link":"https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/","title":{"rendered":"Uitgiften 2026 -Voorverkoop 4 La Louvi\u00e8re"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Nationaal Kampioenschap voor Filatelie<\/p>\n<p>philhainaut&#8217;26 &#038; NumisHainaut&#8217;26<\/p>\n<p>Organisatie: Koninklijke Landsbond der Belgische Postzegelkringen Conseil Philat\u00e9lique Hennuyer<\/p>\n<p>Contact : E-Mail : philhainaut26@gmail.com<\/p>\n<p>Competitieve en propaganda tentoonstellingen, Eresalon \u2013 Postzegeluitgiften &#8211; Tentoonstellingsruimte van 4.000 m\u00b2<\/p>\n<p>Locatie : LOUVEXPO Rue Arthur Delaby 7100 La Louvi\u00e8re Belgium<\/p>\n","protected":false},"author":7,"featured_media":7544,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[18],"tags":[],"class_list":["post-7624","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Uitgiften 2026 -Voorverkoop 4 La Louvi\u00e8re - Bephila<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Uitgiften 2026 -Voorverkoop 4 La Louvi\u00e8re - Bephila\" \/>\n<meta property=\"og:description\" content=\"Nationaal Kampioenschap voor Filatelie philhainaut&#039;26 &amp; NumisHainaut&#039;26 Organisatie: Koninklijke Landsbond der Belgische Postzegelkringen Conseil Philat\u00e9lique Hennuyer Contact : E-Mail : philhainaut26@gmail.com Competitieve en propaganda tentoonstellingen, Eresalon \u2013 Postzegeluitgiften - Tentoonstellingsruimte van 4.000 m\u00b2 Locatie : LOUVEXPO Rue Arthur Delaby 7100 La Louvi\u00e8re Belgium\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/\" \/>\n<meta property=\"og:site_name\" content=\"Bephila\" \/>\n<meta property=\"article:published_time\" content=\"2019-01-30T08:41:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T09:51:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.bephila.be\/wp-content\/uploads\/2022\/12\/Collectieboekje-2026-Cover-A4.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1132\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Veerle VERHELST\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Veerle VERHELST\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.bephila.be\\\/nl\\\/uitgiften-2026-voorverkoop-4-la-louviere\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bephila.be\\\/nl\\\/uitgiften-2026-voorverkoop-4-la-louviere\\\/\"},\"author\":{\"name\":\"Veerle VERHELST\",\"@id\":\"https:\\\/\\\/www.bephila.be\\\/#\\\/schema\\\/person\\\/4bb00dcd0f25a8fd932e5a04c50f765e\"},\"headline\":\"Uitgiften 2026 -Voorverkoop 4 La Louvi\u00e8re\",\"datePublished\":\"2019-01-30T08:41:00+00:00\",\"dateModified\":\"2026-01-30T09:51:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.bephila.be\\\/nl\\\/uitgiften-2026-voorverkoop-4-la-louviere\\\/\"},\"wordCount\":5,\"image\":{\"@id\":\"https:\\\/\\\/www.bephila.be\\\/nl\\\/uitgiften-2026-voorverkoop-4-la-louviere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bephila.be\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Collectieboekje-2026-Cover-A4.webp\",\"articleSection\":[\"News\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.bephila.be\\\/nl\\\/uitgiften-2026-voorverkoop-4-la-louviere\\\/\",\"url\":\"https:\\\/\\\/www.bephila.be\\\/nl\\\/uitgiften-2026-voorverkoop-4-la-louviere\\\/\",\"name\":\"Uitgiften 2026 -Voorverkoop 4 La Louvi\u00e8re - Bephila\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.bephila.be\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.bephila.be\\\/nl\\\/uitgiften-2026-voorverkoop-4-la-louviere\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.bephila.be\\\/nl\\\/uitgiften-2026-voorverkoop-4-la-louviere\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.bephila.be\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Collectieboekje-2026-Cover-A4.webp\",\"datePublished\":\"2019-01-30T08:41:00+00:00\",\"dateModified\":\"2026-01-30T09:51:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.bephila.be\\\/#\\\/schema\\\/person\\\/4bb00dcd0f25a8fd932e5a04c50f765e\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.bephila.be\\\/nl\\\/uitgiften-2026-voorverkoop-4-la-louviere\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.bephila.be\\\/nl\\\/uitgiften-2026-voorverkoop-4-la-louviere\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.bephila.be\\\/nl\\\/uitgiften-2026-voorverkoop-4-la-louviere\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.bephila.be\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Collectieboekje-2026-Cover-A4.webp\",\"contentUrl\":\"https:\\\/\\\/www.bephila.be\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/Collectieboekje-2026-Cover-A4.webp\",\"width\":1600,\"height\":1132},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.bephila.be\\\/nl\\\/uitgiften-2026-voorverkoop-4-la-louviere\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.bephila.be\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Uitgiften 2026 -Voorverkoop 4 La Louvi\u00e8re\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.bephila.be\\\/#website\",\"url\":\"https:\\\/\\\/www.bephila.be\\\/\",\"name\":\"Bephila\",\"description\":\"Association Royale pour la Promotion de la Philat\u00e9lie\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.bephila.be\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.bephila.be\\\/#\\\/schema\\\/person\\\/4bb00dcd0f25a8fd932e5a04c50f765e\",\"name\":\"Veerle VERHELST\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1efa0cfc5820712ce052631569e472c39cce34d303140c1c62c8b69aee0f5279?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1efa0cfc5820712ce052631569e472c39cce34d303140c1c62c8b69aee0f5279?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1efa0cfc5820712ce052631569e472c39cce34d303140c1c62c8b69aee0f5279?s=96&d=mm&r=g\",\"caption\":\"Veerle VERHELST\"},\"url\":\"https:\\\/\\\/www.bephila.be\\\/nl\\\/author\\\/veerle\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Uitgiften 2026 -Voorverkoop 4 La Louvi\u00e8re - Bephila","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/","og_locale":"nl_NL","og_type":"article","og_title":"Uitgiften 2026 -Voorverkoop 4 La Louvi\u00e8re - Bephila","og_description":"Nationaal Kampioenschap voor Filatelie philhainaut'26 & NumisHainaut'26 Organisatie: Koninklijke Landsbond der Belgische Postzegelkringen Conseil Philat\u00e9lique Hennuyer Contact : E-Mail : philhainaut26@gmail.com Competitieve en propaganda tentoonstellingen, Eresalon \u2013 Postzegeluitgiften - Tentoonstellingsruimte van 4.000 m\u00b2 Locatie : LOUVEXPO Rue Arthur Delaby 7100 La Louvi\u00e8re Belgium","og_url":"https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/","og_site_name":"Bephila","article_published_time":"2019-01-30T08:41:00+00:00","article_modified_time":"2026-01-30T09:51:50+00:00","og_image":[{"width":1600,"height":1132,"url":"https:\/\/www.bephila.be\/wp-content\/uploads\/2022\/12\/Collectieboekje-2026-Cover-A4.webp","type":"image\/webp"}],"author":"Veerle VERHELST","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"Veerle VERHELST","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/#article","isPartOf":{"@id":"https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/"},"author":{"name":"Veerle VERHELST","@id":"https:\/\/www.bephila.be\/#\/schema\/person\/4bb00dcd0f25a8fd932e5a04c50f765e"},"headline":"Uitgiften 2026 -Voorverkoop 4 La Louvi\u00e8re","datePublished":"2019-01-30T08:41:00+00:00","dateModified":"2026-01-30T09:51:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/"},"wordCount":5,"image":{"@id":"https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bephila.be\/wp-content\/uploads\/2022\/12\/Collectieboekje-2026-Cover-A4.webp","articleSection":["News"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/","url":"https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/","name":"Uitgiften 2026 -Voorverkoop 4 La Louvi\u00e8re - Bephila","isPartOf":{"@id":"https:\/\/www.bephila.be\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/#primaryimage"},"image":{"@id":"https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/#primaryimage"},"thumbnailUrl":"https:\/\/www.bephila.be\/wp-content\/uploads\/2022\/12\/Collectieboekje-2026-Cover-A4.webp","datePublished":"2019-01-30T08:41:00+00:00","dateModified":"2026-01-30T09:51:50+00:00","author":{"@id":"https:\/\/www.bephila.be\/#\/schema\/person\/4bb00dcd0f25a8fd932e5a04c50f765e"},"breadcrumb":{"@id":"https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/#primaryimage","url":"https:\/\/www.bephila.be\/wp-content\/uploads\/2022\/12\/Collectieboekje-2026-Cover-A4.webp","contentUrl":"https:\/\/www.bephila.be\/wp-content\/uploads\/2022\/12\/Collectieboekje-2026-Cover-A4.webp","width":1600,"height":1132},{"@type":"BreadcrumbList","@id":"https:\/\/www.bephila.be\/nl\/uitgiften-2026-voorverkoop-4-la-louviere\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.bephila.be\/"},{"@type":"ListItem","position":2,"name":"Uitgiften 2026 -Voorverkoop 4 La Louvi\u00e8re"}]},{"@type":"WebSite","@id":"https:\/\/www.bephila.be\/#website","url":"https:\/\/www.bephila.be\/","name":"Bephila","description":"Association Royale pour la Promotion de la Philat\u00e9lie","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.bephila.be\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"https:\/\/www.bephila.be\/#\/schema\/person\/4bb00dcd0f25a8fd932e5a04c50f765e","name":"Veerle VERHELST","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/secure.gravatar.com\/avatar\/1efa0cfc5820712ce052631569e472c39cce34d303140c1c62c8b69aee0f5279?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1efa0cfc5820712ce052631569e472c39cce34d303140c1c62c8b69aee0f5279?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1efa0cfc5820712ce052631569e472c39cce34d303140c1c62c8b69aee0f5279?s=96&d=mm&r=g","caption":"Veerle VERHELST"},"url":"https:\/\/www.bephila.be\/nl\/author\/veerle\/"}]}},"_links":{"self":[{"href":"https:\/\/www.bephila.be\/nl\/wp-json\/wp\/v2\/posts\/7624","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bephila.be\/nl\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bephila.be\/nl\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bephila.be\/nl\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bephila.be\/nl\/wp-json\/wp\/v2\/comments?post=7624"}],"version-history":[{"count":2,"href":"https:\/\/www.bephila.be\/nl\/wp-json\/wp\/v2\/posts\/7624\/revisions"}],"predecessor-version":[{"id":7626,"href":"https:\/\/www.bephila.be\/nl\/wp-json\/wp\/v2\/posts\/7624\/revisions\/7626"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bephila.be\/nl\/wp-json\/wp\/v2\/media\/7544"}],"wp:attachment":[{"href":"https:\/\/www.bephila.be\/nl\/wp-json\/wp\/v2\/media?parent=7624"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bephila.be\/nl\/wp-json\/wp\/v2\/categories?post=7624"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bephila.be\/nl\/wp-json\/wp\/v2\/tags?post=7624"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}